{"id":5749,"date":"2020-01-19T18:31:40","date_gmt":"2020-01-19T17:31:40","guid":{"rendered":"https:\/\/kehl.dakd.de\/?p=5749"},"modified":"2020-07-29T18:43:39","modified_gmt":"2020-07-29T16:43:39","slug":"wort-zum-sonntag-am-19-01-2020","status":"publish","type":"post","link":"https:\/\/kehl.dakd.de\/am\/2020\/01\/19\/wort-zum-sonntag-am-19-01-2020\/","title":{"rendered":"Wort zum Sonntag am 19.01.2020"},"content":{"rendered":"<p><img decoding=\"async\" class=\"size-fusion-600 wp-image-5603 alignnone\" src=\"http:\/\/kehl.dakd.de\/wp-content\/uploads\/2020\/07\/WortZumSonntag-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/p>\n<p><strong>\u201eDas Ziel der Unterweisung ist Liebe aus reinem Herzen,<br \/>\ngutem Gewissen und ungeheucheltem Glauben.\u201c (<a href=\"https:\/\/www.bibleserver.com\/EU\/1.Timotheus1%2C5\" class=\"bibleserver extern\" target=\"_blank\" rel=\"noopener noreferrer\">1 Tim. 1, 5<\/a>)<\/strong><\/p>\n<p>Liebe Schwestern und Br\u00fcder,<br \/>\nder morgige Sonntag ist gem\u00e4\u00df dem armenischen Kirchenkalender der 1. Sonntag nach Weihnachten. Rund vor zwei Wochen, am 6. Januar, haben wir Weihnachten gefeiert und einander die frohe Botschaft der Geburt und Gottesoffenbarung des Herrn weitergegeben. Diese frohe Botschaft ist, dass \u201eGott in Christus Jesus Mensch geworden ist\u201c, dass Gott sich in Jesus Christus der Menschheit offenbart und durch ihn zu uns und f\u00fcr uns gesprochen hat.<\/p>\n<p>Diese frohe Botschaft wird uns auch durch die Lekt\u00fcre verschiedener Abschnitte aus der Bibel verk\u00fcndet, ob in der Kirche oder au\u00dferhalb. Unser kirchlicher Kalender ist so gestaltet, dass es jeden Tag in der Kirche bestimmte Abschnitte der Heiligen Schrift den Gl\u00e4ubigen vorgelesen werden. Eine der f\u00fcr den morgigen Sonntag bestimmten Lesungen ist ein Abschnitt aus dem 1. Brief des Apostels Paulus an Timotheus, aus der ich die \u00dcberschrift dieser kurzen Predigt entnommen habe.<\/p>\n<p>Die Bibel verk\u00fcndet uns viele Gebote, die uns den Willen Gottes mitteilen und uns einladen, diese Gebote zu halten und nach ihnen zu leben. Aber die Haltung der Gottesgebote sollte nicht eine Folge der Angst sein, sondern Ergebnis eines liebevollen Herzens. Wer die Gebote aus Angst vor Bestrafung h\u00e4lt, h\u00e4lt im wahrsten Sinne die Gebote nicht. Die Angst kann uns eventuell davon abhalten, schlechte Dinge oder gar B\u00f6ses zu tun, sie kann aber laut der Bibel niemals das richtige Motiv sein, Gottes Willen zu verwirklichen.<\/p>\n<p>Die Einhaltung der Gebote soll ein Ergebnis der Liebe gegen\u00fcber Gott und den Menschen sein, welche \u201eaus reinem Herzen, gutem Gewissen und ungeheucheltem Glauben\u201c hervorgeht. Sonst kann jeder von uns sich sehr schnell zum eingebildeten und egozentrischen Pharis\u00e4er umwandeln. Unsere Lebensweise, unsere Taten und Handeln sind wichtig, aber viel wichtiger sind die Liebe zu Gott, unserem Sch\u00f6pfer und zum von Ihm geschaffenen Menschen, die Reinheit unseres Herzens und unser aufrichtiger Glaube. Nur so kann ein Christ ein frommes Leben f\u00fchren und eine harmonische Beziehung zu Gott, zum eigenen Herzen und seinem Leben aufbauen. Und auf diese Weise w\u00fcrden wir nicht nur zu Gott beten und sagen: \u201eDein Wille geschehe wie im Himmel und so auf Erden\u201c, sondern w\u00e4ren wir die wahren Verwirklicher Seines Willens. Amen.<\/p>\n<p>Liebe Schwestern und Br\u00fcder,<br \/>\nab heute werden wir jeden Samstagabend, auf unserer Facebook-Seite, einen geistlichen Impuls, verfasst von einem Geistlichen unserer Di\u00f6zese, zum Thema einer der Tageslesungen des anbrechenden Sonntags posten. Wir w\u00fcrden uns freuen, wenn diese Impulse Euch helfen, kurz inne zu halten. Vielen Dank und Gott beh\u00fcte uns alle!<\/p>\n<p>Serovpe Srpazan<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201eDas Ziel der Unterweisung ist Liebe aus reinem Herzen, gutem  [&#8230;]<\/p>\n","protected":false},"author":12,"featured_media":6580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121,107],"tags":[],"class_list":["post-5749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bischof","category-glaubensfragen"],"_links":{"self":[{"href":"https:\/\/kehl.dakd.de\/am\/wp-json\/wp\/v2\/posts\/5749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kehl.dakd.de\/am\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kehl.dakd.de\/am\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kehl.dakd.de\/am\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/kehl.dakd.de\/am\/wp-json\/wp\/v2\/comments?post=5749"}],"version-history":[{"count":0,"href":"https:\/\/kehl.dakd.de\/am\/wp-json\/wp\/v2\/posts\/5749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kehl.dakd.de\/am\/wp-json\/wp\/v2\/media\/6580"}],"wp:attachment":[{"href":"https:\/\/kehl.dakd.de\/am\/wp-json\/wp\/v2\/media?parent=5749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kehl.dakd.de\/am\/wp-json\/wp\/v2\/categories?post=5749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kehl.dakd.de\/am\/wp-json\/wp\/v2\/tags?post=5749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}